{"id":9931,"date":"2023-02-16T11:00:00","date_gmt":"2023-02-16T10:00:00","guid":{"rendered":"https:\/\/tedxvitoriagasteiz.com\/es\/?p=9931"},"modified":"2023-02-16T11:30:38","modified_gmt":"2023-02-16T10:30:38","slug":"charlas-ted-para-un-mundo-equitativo","status":"publish","type":"post","link":"https:\/\/tedxvitoriagasteiz.com\/es\/charlas\/charlas-ted-para-un-mundo-equitativo\/cristina\/","title":{"rendered":"6 charlas TEDx para un mundo m\u00e1s equitativo"},"content":{"rendered":"\n<p>Vivimos en una \u00e9poca de enorme progreso social y econ\u00f3mico y, sin embargo, la desigualdad se mantiene en los mismos niveles de hace un siglo. Algo falla en nuestra sociedad y en nosotros.\u00a0Hemos recopilado seis charlas TED para reflexionar sobre <strong>un mundo m\u00e1s equitativo<\/strong>.<\/p>\n<p>Estas charlas abordan temas dispares pero todas ellas reflejan las desigualdades de la sociedad. Algunas ofrecen respuestas y otras nos plantean preguntas que deber\u00edamos poder contestar.\u00a0<\/p>\n<p>Es necesario repensar en qu\u00e9 sociedad queremos vivir y, sobre todo, dejar a nuestros hijos.<\/p>\n<h2 class=\"mt-4 mr-8 flex w-full flex-row flex-wrap items-center pb-5 md:mt-10 md:flex-nowrap\">\u00bfFuncionan las vallas para detener la migraci\u00f3n? | Dani Villanueva<\/h2>\n<div>Si has vivido lo suficiente, es probable que recuerdes el muro de Berl\u00edn y su ca\u00edda en 1989. Por entonces hab\u00eda 16 muros o vallas en el mundo.<\/div>\n<div>\u00a0<\/div>\n<div>\u00bfHoy en d\u00eda? Casi 70 muros. Europa tiene cerca de mil kil\u00f3metros de muros en sus fronteras. Dos de esos muros est\u00e1n aqu\u00ed en Espa\u00f1a: las vallas de Ceuta y Melilla.<\/div>\n<div>\u00a0<\/div>\n<div>Vallas que hacen de frontera para detener flujos humanos que huyen de la guerra, la represi\u00f3n, el hambre, la enfermedad&#8230; La pregunta es: \u00bffuncionan?<\/div>\n<div>\u00a0<\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div  id=\"_ytid_74234\" class=\"__youtube_prefs__  __youtube_prefs_gdpr__  epyt-is-override \" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><p><strong>Necesitas aceptar las cookies de YouTube para ver este v\u00eddeo<\/strong>. Al aceptarlas, acceder\u00e1s al contenido de YouTube que es un servicio externo a la web.<\/p>\n<p><a href=\"https:\/\/policies.google.com\/privacy?hl=es\" target=\"_blank\" rel=\"noopener\">YouTube privacy policy<\/a><\/p>\n<p>Si aceptas, la p\u00e1gina se refrescar\u00e1 para que puedas ver el v\u00eddeo.<\/p>\n<button type=\"button\" class=\"__youtube_prefs_gdpr__\">Aceptar Cookies de YouTube<img decoding=\"async\" src=\"https:\/\/tedxvitoriagasteiz.com\/wp-content\/plugins\/youtube-embed-plus\/images\/icon-check.png\" alt=\"accept\" data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\" \/><\/button><\/div>\n<\/div><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Who rescues who: the Story of Aquarius | Anelise Borges<\/h2>\n\n\n\n<p>En 2018, Anelise Borges pas\u00f3 10 d\u00edas a bordo del Aquarius (de la ONG <a href=\"https:\/\/en.sosmediterranee.org\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"broken_link\">Sosmediterranee<\/a>). Un barco de rescate con 629 migrantes a bordo al que se le prohibi\u00f3 atracar en puertos de Italia y Francia. Tras intensas negociaciones a nivel europe, se le permiti\u00f3 atracar en Valencia.<\/p>\n\n\n\n<p><strong>Anelise relata su experiencia donde los l\u00edmites entre lo profesional y lo humano se funden<\/strong>. Una historia de rescate, de valent\u00eda y de vida.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div  id=\"_ytid_62364\" class=\"__youtube_prefs__  __youtube_prefs_gdpr__  epyt-is-override \" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><p><strong>Necesitas aceptar las cookies de YouTube para ver este v\u00eddeo<\/strong>. Al aceptarlas, acceder\u00e1s al contenido de YouTube que es un servicio externo a la web.<\/p>\n<p><a href=\"https:\/\/policies.google.com\/privacy?hl=es\" target=\"_blank\" rel=\"noopener\">YouTube privacy policy<\/a><\/p>\n<p>Si aceptas, la p\u00e1gina se refrescar\u00e1 para que puedas ver el v\u00eddeo.<\/p>\n<button type=\"button\" class=\"__youtube_prefs_gdpr__\">Aceptar Cookies de YouTube<img decoding=\"async\" src=\"https:\/\/tedxvitoriagasteiz.com\/wp-content\/plugins\/youtube-embed-plus\/images\/icon-check.png\" alt=\"accept\" data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\" \/><\/button><\/div>\n<\/div><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>How we talk about sexual assault online | Ione Wells<\/strong><\/h2>\n\n\n\n<p>Volviendo de una cena con unos amigos, Ione sufri\u00f3 una agresi\u00f3n sexual en la calle a pocos metros de su casa. Como forma de gestionar lo sucedido, escribi\u00f3 una carta a su asaltante que public\u00f3 en un peri\u00f3dico estudiantil.<\/p>\n\n\n\n<p>La carta se hizo viral y dio lugar a la campa\u00f1a #NotGuilty (#NoSoyCulpable) donde se animaba a otras v\u00edctimas a alzar su voz en lugar de permanecer calladas por miedo o verg\u00fcenza y contra la revictimizaci\u00f3n. La respuestas en Internet le llamaron mucho la atenci\u00f3n.<\/p>\n\n\n\n<p>Una charla que ahonda en c\u00f3mo reaccionamos en Internet a situaciones similares y nuestra responsabilidad.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div  id=\"_ytid_81193\" class=\"__youtube_prefs__  __youtube_prefs_gdpr__  epyt-is-override \" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><p><strong>Necesitas aceptar las cookies de YouTube para ver este v\u00eddeo<\/strong>. Al aceptarlas, acceder\u00e1s al contenido de YouTube que es un servicio externo a la web.<\/p>\n<p><a href=\"https:\/\/policies.google.com\/privacy?hl=es\" target=\"_blank\" rel=\"noopener\">YouTube privacy policy<\/a><\/p>\n<p>Si aceptas, la p\u00e1gina se refrescar\u00e1 para que puedas ver el v\u00eddeo.<\/p>\n<button type=\"button\" class=\"__youtube_prefs_gdpr__\">Aceptar Cookies de YouTube<img decoding=\"async\" src=\"https:\/\/tedxvitoriagasteiz.com\/wp-content\/plugins\/youtube-embed-plus\/images\/icon-check.png\" alt=\"accept\" data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\" \/><\/button><\/div>\n<\/div><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El violador eres t\u00fa | J\u00e9ssica Fillol<\/strong><\/h2>\n\n\n\n<p>\u00bfQui\u00e9n comete las violaciones? Los datos dicen que, en la mayor\u00eda de los casos, no son encapuchados en callejones oscuros en plena noche con una navaja. En el 90% de las violaciones, el agresor conoce a la v\u00edctima. <\/p>\n\n\n\n<p>Entonces, \u00bfpor qu\u00e9 la sociedad insiste en identificar una figura que no es responsable de la mayor\u00eda de los casos y despu\u00e9s responsabilizar a la mujer de su comportamiento?<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div  id=\"_ytid_86404\" class=\"__youtube_prefs__  __youtube_prefs_gdpr__  epyt-is-override \" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><p><strong>Necesitas aceptar las cookies de YouTube para ver este v\u00eddeo<\/strong>. Al aceptarlas, acceder\u00e1s al contenido de YouTube que es un servicio externo a la web.<\/p>\n<p><a href=\"https:\/\/policies.google.com\/privacy?hl=es\" target=\"_blank\" rel=\"noopener\">YouTube privacy policy<\/a><\/p>\n<p>Si aceptas, la p\u00e1gina se refrescar\u00e1 para que puedas ver el v\u00eddeo.<\/p>\n<button type=\"button\" class=\"__youtube_prefs_gdpr__\">Aceptar Cookies de YouTube<img decoding=\"async\" src=\"https:\/\/tedxvitoriagasteiz.com\/wp-content\/plugins\/youtube-embed-plus\/images\/icon-check.png\" alt=\"accept\" data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\" \/><\/button><\/div>\n<\/div><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La urgencia de la interseccionalidad | Kimberl\u00e9 Crenshaw<\/strong><\/h2>\n\n\n\n<p>Cuando se producen dos o m\u00e1s circunstancias de discriminaci\u00f3n en una persona o colectivo hablamos de interseccionalidad. Un t\u00e9rmino que acu\u00f1\u00f3 hace a\u00f1os Kimberl\u00e9 Crenshaw, defensora estadounidense de los derechos humanos, para nombrar la discriminaci\u00f3n m\u00faltiple que sufr\u00edan, y sufren, las mujeres afroamericanas en Estados Unidos por su g\u00e9nero y raza.<\/p>\n\n\n\n<p>Una situaci\u00f3n que no nos puede resultar extra\u00f1a aqu\u00ed. Un ejemplo: las mujeres migrantes o racializadas.<\/p>\n\n\n\n<p>Una charla que nos invita a la reflexi\u00f3n y nos urge a adoptar una mirada m\u00e1s completa.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-ted wp-block-embed-ted wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Kimberl\u00e9 Crenshaw: The urgency of intersectionality\" src=\"https:\/\/embed.ted.com\/talks\/kimberle_crenshaw_the_urgency_of_intersectionality\" width=\"1777\" height=\"1000\" frameborder=\"0\" scrolling=\"no\" webkitAllowFullScreen mozallowfullscreen allowFullScreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">How economic inequality harms societies | Richard Wilkinson<\/h2>\n\n\n\n<p><strong>La desigualdad econ\u00f3mica perjudica a la sociedad.<\/strong> No es una teor\u00eda ni un lema. Es una realidad sustentada en datos de Naciones Unidas, la OMS o el Banco Mundial entre otras muchas organizaciones y en multitud de estudios econ\u00f3micos.<\/p>\n\n\n\n<p>Richard Wilkinson sostiene que a mayor desigualdad econ\u00f3mica, peores son los problemas sociales, y que esta situaci\u00f3n se reflejan en la educaci\u00f3n, la esperanza de vida, la sanidad, la seguridad ciudadana&#8230; <\/p>\n\n\n\n<p>En las econom\u00edas desarrolladas, el bienestar social de un pa\u00eds ya no depende de su crecimiento econ\u00f3mico sino del grado de desigualdad econ\u00f3mica que tenga. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-ted wp-block-embed-ted wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Richard Wilkinson: How economic inequality harms societies\" src=\"https:\/\/embed.ted.com\/talks\/richard_wilkinson_how_economic_inequality_harms_societies\" width=\"1777\" height=\"1000\" frameborder=\"0\" scrolling=\"no\" webkitAllowFullScreen mozallowfullscreen allowFullScreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2>\u00bfHay esperanza para conseguir un mundo m\u00e1s equitativo?<\/h2>\n<p>Sin duda la hay. Vivimos en un momento de hiperconexi\u00f3n y de inmediatez. Y precisamente estas pueden ser algunas de las herramientas que nos ayuden a poner soluci\u00f3n a los problemas que tenemos como sociedad y lograr as\u00ed <strong>un mundo m\u00e1s equitativo<\/strong>.<\/p>\n<p>\u00bfTe apuntas a la soluci\u00f3n con nosotros?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivimos en una \u00e9poca de enorme progreso social y econ\u00f3mico y, sin embargo, la desigualdad se mantiene en los mismos niveles de hace un siglo.&hellip; <\/p>\n","protected":false},"author":2,"featured_media":10059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[203,223],"tags":[237,206,97],"_links":{"self":[{"href":"https:\/\/tedxvitoriagasteiz.com\/es\/wp-json\/wp\/v2\/posts\/9931"}],"collection":[{"href":"https:\/\/tedxvitoriagasteiz.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tedxvitoriagasteiz.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tedxvitoriagasteiz.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tedxvitoriagasteiz.com\/es\/wp-json\/wp\/v2\/comments?post=9931"}],"version-history":[{"count":9,"href":"https:\/\/tedxvitoriagasteiz.com\/es\/wp-json\/wp\/v2\/posts\/9931\/revisions"}],"predecessor-version":[{"id":10063,"href":"https:\/\/tedxvitoriagasteiz.com\/es\/wp-json\/wp\/v2\/posts\/9931\/revisions\/10063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tedxvitoriagasteiz.com\/es\/wp-json\/wp\/v2\/media\/10059"}],"wp:attachment":[{"href":"https:\/\/tedxvitoriagasteiz.com\/es\/wp-json\/wp\/v2\/media?parent=9931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tedxvitoriagasteiz.com\/es\/wp-json\/wp\/v2\/categories?post=9931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tedxvitoriagasteiz.com\/es\/wp-json\/wp\/v2\/tags?post=9931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}